{"id":21699,"date":"2024-02-09T15:15:16","date_gmt":"2024-02-09T15:15:16","guid":{"rendered":"https:\/\/brunavasconcelos.pt\/?post_type=product&#038;p=21699"},"modified":"2026-01-29T02:57:10","modified_gmt":"2026-01-29T02:57:10","slug":"hoop-little-flowers","status":"publish","type":"product","link":"https:\/\/brunavasconcelos.pt\/es\/product\/hoop-little-flowers\/","title":{"rendered":"Pendientes Little Flowers"},"content":{"rendered":"<p>Modernos, delicados e irreverentes, son anillos frontales con detalles florales y toques de brillo y color.<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates y circonitas<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Modernos, delicados e irreverentes, son anillos frontales con detalles florales y toques de brillo y color.<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates y circonitas<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":23793,"template":"","meta":[],"product_brand":[],"product_cat":[215,284],"product_tag":[220],"class_list":["post-21699","product","type-product","status-publish","has-post-thumbnail","product_cat-brincos","product_cat-ultimas-unidades","product_tag-gift","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-variable"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product\/21699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media\/23793"}],"wp:attachment":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media?parent=21699"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_brand?post=21699"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_cat?post=21699"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_tag?post=21699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}