{"id":21751,"date":"2024-02-09T17:55:36","date_gmt":"2024-02-09T17:55:36","guid":{"rendered":"https:\/\/brunavasconcelos.pt\/?post_type=product&#038;p=21751"},"modified":"2026-01-29T02:55:37","modified_gmt":"2026-01-29T02:55:37","slug":"anel-candy-five","status":"publish","type":"product","link":"https:\/\/brunavasconcelos.pt\/es\/product\/anel-candy-five\/","title":{"rendered":"Anillo Candy Five"},"content":{"rendered":"<p>La colecci\u00f3n m\u00e1s dulce y colorida de Bruna Vasconcelos, en plata y plata dorada, en la que destacan los elementos principales: circonitas de diferentes colores, formas sencillas para realzar el uso del color.<\/p>\n<p>Perfecta para todos los d\u00edas, para llevar sola o mezclada con otras joyas, vers\u00e1til, moderna y a la vez atemporal, \u00a1una joya que no puede faltar en su colecci\u00f3n!<\/p>\n<p>Del\u00e9itese con esta exclusiva colecci\u00f3n de BV.<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates y circonitas<\/p>\n<p>Anillo de medici\u00f3n ajustable<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>La colecci\u00f3n m\u00e1s dulce y colorida de Bruna Vasconcelos, en plata y plata dorada, en la que destacan los elementos principales: circonitas de diferentes colores, formas sencillas para realzar el uso del color.<\/p>\n<p>Perfecta para todos los d\u00edas, para llevar sola o mezclada con otras joyas, vers\u00e1til, moderna y a la vez atemporal, \u00a1una joya que no puede faltar en su colecci\u00f3n!<\/p>\n<p>Del\u00e9itese con esta colecci\u00f3n exclusiva de BV<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates y circonitas<\/p>\n<p>Anillo de medici\u00f3n ajustable<\/p>","protected":false},"featured_media":21714,"template":"","meta":[],"product_brand":[],"product_cat":[213,284],"product_tag":[],"class_list":["post-21751","product","type-product","status-publish","has-post-thumbnail","product_cat-aneis","product_cat-ultimas-unidades","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-variable"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product\/21751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media?parent=21751"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_brand?post=21751"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_cat?post=21751"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_tag?post=21751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}