{"id":21781,"date":"2024-02-09T18:14:56","date_gmt":"2024-02-09T18:14:56","guid":{"rendered":"https:\/\/brunavasconcelos.pt\/?post_type=product&#038;p=21781"},"modified":"2026-04-25T17:30:49","modified_gmt":"2026-04-25T17:30:49","slug":"say-my-name-b","status":"publish","type":"product","link":"https:\/\/brunavasconcelos.pt\/es\/product\/say-my-name-b\/","title":{"rendered":"Collar Say my Name"},"content":{"rendered":"<p>Say my Name , la colecci\u00f3n que firma tu nombre, tu individualidad, el nombre de alguien querido o un lugar especial, \u00bfqu\u00e9 letra ser\u00e1 tu amuleto?<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates<\/p>\n<p>Incluye una cadena de 40 cm de largo y una extensi\u00f3n de 5 cm<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Say my Name , la colecci\u00f3n que firma tu nombre, tu individualidad, el nombre de alguien querido o un lugar especial, \u00bfqu\u00e9 letra ser\u00e1 tu amuleto?<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates<\/p>\n<p>Incluye una cadena de 40 cm de largo y una extensi\u00f3n de 5 cm<\/p>","protected":false},"featured_media":21757,"template":"","meta":[],"product_brand":[],"product_cat":[274,214],"product_tag":[224],"class_list":["post-21781","product","type-product","status-publish","has-post-thumbnail","product_cat-classicos","product_cat-colares","product_tag-iniciais","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-variable"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product\/21781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media\/21757"}],"wp:attachment":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media?parent=21781"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_brand?post=21781"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_cat?post=21781"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_tag?post=21781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}