{"id":22047,"date":"2024-02-10T13:12:18","date_gmt":"2024-02-10T13:12:18","guid":{"rendered":"https:\/\/brunavasconcelos.pt\/?post_type=product&#038;p=22047"},"modified":"2026-01-29T02:51:12","modified_gmt":"2026-01-29T02:51:12","slug":"anel-mo","status":"publish","type":"product","link":"https:\/\/brunavasconcelos.pt\/es\/product\/anel-mo\/","title":{"rendered":"Anillo M\u00f3"},"content":{"rendered":"<p>Anel M\u00f3, com a sua estrela texturada no topo do aro, destaca a irc\u00f3nia incolor no seu centro e um a beleza estonteante<\/p>\n<p>Anillo de medici\u00f3n ajustable<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates y circonitas<\/p>","protected":false},"excerpt":{"rendered":"<p>Anel M\u00f3, com a sua estrela texturada no topo do aro, destaca a irc\u00f3nia incolor no seu centro e um a beleza estonteante<\/p>\n<p>Anillo de medici\u00f3n ajustable<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates y circonitas<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":21983,"template":"","meta":[],"product_brand":[],"product_cat":[213,233],"product_tag":[219],"class_list":["post-22047","product","type-product","status-publish","has-post-thumbnail","product_cat-aneis","product_cat-raiz","product_tag-cerimonia","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product\/22047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media\/21983"}],"wp:attachment":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media?parent=22047"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_brand?post=22047"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_cat?post=22047"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_tag?post=22047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}