{"id":22067,"date":"2024-02-10T19:49:39","date_gmt":"2024-02-10T19:49:39","guid":{"rendered":"https:\/\/brunavasconcelos.pt\/?post_type=product&#038;p=22067"},"modified":"2026-07-13T12:57:52","modified_gmt":"2026-07-13T12:57:52","slug":"anel-bella","status":"publish","type":"product","link":"https:\/\/brunavasconcelos.pt\/es\/product\/anel-bella\/","title":{"rendered":"Anillo Bella"},"content":{"rendered":"<p>El anillo Bella es una joya cl\u00e1sica y atemporal, con tres circonitas ovaladas intercaladas con dos talla navette. Es la pieza que pasar\u00e1 de generaci\u00f3n en generaci\u00f3n y celebrar\u00e1 los momentos m\u00e1s especiales.<\/p>\n<p>El tama\u00f1o del anillo es ajustable<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates y circonitas<\/p>","protected":false},"excerpt":{"rendered":"<p>El anillo Bella es una joya cl\u00e1sica y atemporal, con tres circonitas ovaladas intercaladas con dos talla navette. Es la pieza que pasar\u00e1 de generaci\u00f3n en generaci\u00f3n y celebrar\u00e1 los momentos m\u00e1s especiales.<\/p>\n<p>El tama\u00f1o del anillo es ajustable<\/p>\n<p>&nbsp;<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates y circonitas<\/p>","protected":false},"featured_media":22967,"template":"","meta":[],"product_brand":[],"product_cat":[213,274],"product_tag":[243,219,265,258,220,261,237,264],"class_list":["post-22067","product","type-product","status-publish","has-post-thumbnail","product_cat-aneis","product_cat-classicos","product_tag-anel","product_tag-cerimonia","product_tag-engagement","product_tag-festa","product_tag-gift","product_tag-joias-statement","product_tag-noivado","product_tag-ring","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-variable"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product\/22067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media\/22967"}],"wp:attachment":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media?parent=22067"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_brand?post=22067"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_cat?post=22067"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_tag?post=22067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}