{"id":22111,"date":"2024-02-15T17:23:04","date_gmt":"2024-02-15T17:23:04","guid":{"rendered":"https:\/\/brunavasconcelos.pt\/?post_type=product&#038;p=22111"},"modified":"2024-11-30T20:37:27","modified_gmt":"2024-11-30T20:37:27","slug":"brincos-sweet-love","status":"publish","type":"product","link":"https:\/\/brunavasconcelos.pt\/es\/product\/brincos-sweet-love\/","title":{"rendered":"Pendientes Sweet Love"},"content":{"rendered":"<p>Brincos de tamanho m\u00e9dio, para usar junto ao l\u00f3bulo, leves, confort\u00e1veis e elegantes, uma joia para todos os dias.<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates<\/p>","protected":false},"excerpt":{"rendered":"<p>Brincos de tamanho m\u00e9dio, para usar junto ao l\u00f3bulo, leves, confort\u00e1veis e elegantes, uma joia para todos os dias.<\/p>\n<p>Plata 925 ba\u00f1ada en oro de 24 quilates<\/p>","protected":false},"featured_media":22112,"template":"","meta":[],"product_brand":[],"product_cat":[215,231,238],"product_tag":[219,218],"class_list":["post-22111","product","type-product","status-publish","has-post-thumbnail","product_cat-brincos","product_cat-colecoes","product_cat-romance-colecoes","product_tag-cerimonia","product_tag-noivas","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product\/22111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media\/22112"}],"wp:attachment":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media?parent=22111"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_brand?post=22111"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_cat?post=22111"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_tag?post=22111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}