{"id":23141,"date":"2024-12-12T21:00:01","date_gmt":"2024-12-12T21:00:01","guid":{"rendered":"https:\/\/brunavasconcelos.pt\/?post_type=product&#038;p=23141"},"modified":"2025-12-16T19:45:04","modified_gmt":"2025-12-16T19:45:04","slug":"colar-fausto","status":"publish","type":"product","link":"https:\/\/brunavasconcelos.pt\/es\/product\/colar-fausto\/","title":{"rendered":"Colar Fausto"},"content":{"rendered":"<p class=\"p1\">Da competi\u00e7\u00e3o divina, Atena plantou na terra f\u00e9rtil da acr\u00f3pole, uma semente de onde surgiu uma magn\u00edfica oliveira que deu ramos fortes e generosos em sombra e frutos.<\/p>\n<p class=\"p1\">S\u00edmbolo de lealdade, for\u00e7a e resist\u00eancia, a oliveira representa sabedoria.<\/p>\n<p class=\"p3\">O legado duradouro da d\u00e1diva de Atena s\u00e3o um\u00a0testamento de que a verdadeira sabedoria engloba uma\u00a0profunda compreens\u00e3o das necessidades e aspira\u00e7\u00f5es daqueles que est\u00e3o sob sua prote\u00e7\u00e3o.<\/p>\n<p>Colar em prata 925 com banho de ouro 24k<\/p>\n<p>Medidas: 1.7 X 1.7 x 0.3<\/p>\n<p>Corrente: 40cm + 5cm extens\u00e3o<\/p>\n<p>Peso: 2.15gr<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Da competi\u00e7\u00e3o divina, Atena plantou na terra f\u00e9rtil da acr\u00f3pole, uma semente de onde surgiu uma magn\u00edfica oliveira que deu ramos fortes e generosos em sombra e frutos.<\/p>\n<p class=\"p1\">S\u00edmbolo de lealdade, for\u00e7a e resist\u00eancia, a oliveira representa sabedoria.<\/p>\n<p class=\"p3\">O legado duradouro da d\u00e1diva de Atena s\u00e3o um\u00a0testamento de que a verdadeira sabedoria engloba uma\u00a0profunda compreens\u00e3o das necessidades e aspira\u00e7\u00f5es daqueles que est\u00e3o sob sua prote\u00e7\u00e3o.<\/p>\n<p>Colar em prata 925 com banho de ouro 24k<\/p>\n<p>Medidas: 1.7 X 1.7 x 0.3<\/p>\n<p>Corrente: 40cm + 5cm extens\u00e3o<\/p>\n<p>Peso: 2.15gr<\/p>","protected":false},"featured_media":23123,"template":"","meta":[],"product_brand":[],"product_cat":[270,214],"product_tag":[244],"class_list":["post-23141","product","type-product","status-publish","has-post-thumbnail","product_cat-athena","product_cat-colares","product_tag-colar","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product\/23141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media\/23123"}],"wp:attachment":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media?parent=23141"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_brand?post=23141"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_cat?post=23141"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_tag?post=23141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}