{"id":23348,"date":"2025-03-18T17:28:17","date_gmt":"2025-03-18T17:28:17","guid":{"rendered":"https:\/\/brunavasconcelos.pt\/?post_type=product&#038;p=23348"},"modified":"2025-03-26T11:45:04","modified_gmt":"2025-03-26T11:45:04","slug":"toucado-margot","status":"publish","type":"product","link":"https:\/\/brunavasconcelos.pt\/es\/product\/toucado-margot\/","title":{"rendered":"Toucado Margot"},"content":{"rendered":"<p>Uma joia com presen\u00e7a e detalhe que a vai surpreender.<\/p>\n<p>Aproximadamente 12cm de comprimento,\u00a0 segura com travessa.<\/p>\n<p>Plazo medio de entrega de 15 d\u00edas laborables<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Todos los accesorios para el cabello se a\u00f1aden a petici\u00f3n del cliente, que puede variar en funci\u00f3n del peinado. Todas las piezas se pueden personalizar y hacer por encargo, los tocados son \u00fanicos e irrepetibles.<\/p>\n<p>Si desea m\u00e1s informaci\u00f3n, p\u00f3ngase en contacto con nosotros en geral@bvjewellery.pt<\/p>\n<p>No aceptamos cambios ni devoluciones de estos art\u00edculos.<\/p>","protected":false},"featured_media":23350,"template":"","meta":[],"product_brand":[],"product_cat":[246,231,232,247],"product_tag":[219,249,248],"class_list":["post-23348","product","type-product","status-publish","has-post-thumbnail","product_cat-bride","product_cat-colecoes","product_cat-joias","product_cat-toucados","product_tag-cerimonia","product_tag-noiva","product_tag-toucado","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product\/23348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media\/23350"}],"wp:attachment":[{"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/media?parent=23348"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_brand?post=23348"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_cat?post=23348"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brunavasconcelos.pt\/es\/wp-json\/wp\/v2\/product_tag?post=23348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}